{"id":202,"count":47,"description":"I nostri kit di pressatura aggiungono croccantezza e consistenza ai vostri piatti. Ogni kit comprende un pressatore in silicone alimentare Mold che si abbina con precisione a uno stencil. Sfogliate i nostri diversi kit e trasformate le superfici piatte in texture dettagliate e uniche.","link":"https:\/\/shop.moldbrothers.com\/it\/categoria-prodotto-2\/pressing-kits\/","name":"Kit di pressatura","slug":"pressing-kits","taxonomy":"product_cat","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/shop.moldbrothers.com\/it\/wp-json\/wp\/v2\/product_cat\/202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shop.moldbrothers.com\/it\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/shop.moldbrothers.com\/it\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/shop.moldbrothers.com\/it\/wp-json\/wp\/v2\/product?product_cat=202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}